{"id":1255,"date":"2023-03-07T11:44:45","date_gmt":"2023-03-07T11:44:45","guid":{"rendered":"https:\/\/sonamines.cm\/?p=1255"},"modified":"2023-03-07T12:53:23","modified_gmt":"2023-03-07T12:53:23","slug":"pdac-2023-la-sonamines-assure-la-visibilite-du-cameroun","status":"publish","type":"post","link":"https:\/\/sonamines.cm\/en\/pdac-2023-la-sonamines-assure-la-visibilite-du-cameroun\/","title":{"rendered":"PDAC 2023 : La SONAMINES assure la visibilit\u00e9 du Cameroun"},"content":{"rendered":"<p><em>Le bras op\u00e9rationnel de l\u2019Etat brave les temp\u00e9ratures hivernales de la ville de Toronto au Canada, pour mettre en vitrine le potentiel minier de notre pays afin d\u2019y attirer le maximum d\u2019investisseurs.<\/em><\/p>\n<p>Le Directeur G\u00e9n\u00e9ral de la Soci\u00e9t\u00e9 Nationale des Mines, Serges Herv\u00e9 Boyogueno, conduit une d\u00e9l\u00e9gation de l\u2019entreprise dont il a la charge au <strong>Prospectors and Developpers Association of Canada Convention (PDAC)<\/strong>, le plus grand \u00e9v\u00e8nement sur l\u2019exploration et l\u2019exploitation mini\u00e8re et les industries connexes au monde. Au compteur cette ann\u00e9e, pr\u00e8s de 1100 exposants et des milliers de visiteurs, tous motiv\u00e9s dans ce contexte d\u2019apr\u00e8s covid, de trouver pour les uns des nouvelles niches d\u2019investissement et pour les autres de nouveaux partenaires pour d\u00e9velopper des projets. A c\u00f4t\u00e9 de cela, il y a les grands pays \u00e0 forte tradition mini\u00e8re qui se d\u00e9ploient pour mettre en avant leur exp\u00e9rience et leur know how.<\/p>\n<p>Depuis le dimanche 05 mars 2023 et ce jusqu\u2019au mercredi 08 au Metro Toronto Convention Center, la <strong>Soci\u00e9t\u00e9 Nationale des Mines <\/strong>ne fait pas l\u2019\u00e9conomie d\u2019arguments, des cartes mini\u00e8res et \u00e9chantillons \u00e0 l\u2019appui pour valoriser le sous-sol camerounais sous exploit\u00e9 au stand 923. Une occasion pour la jeune entreprise de mettre en \u0153uvre ses missions de promotion de l\u2019information g\u00e9ologique et mini\u00e8re, mais aussi et surtout de proposer son expertise pour l\u2019accompagnement des potentiels partenaires d\u00e9sirant s\u2019installer au Cameroun. Le Directeur G\u00e9n\u00e9ral profite \u00e9galement de cette opportunit\u00e9, pour poursuivre les \u00e9changes entam\u00e9s \u00e0 Cape Town en Afrique du Sud avec certaines soci\u00e9t\u00e9s mini\u00e8res de renom.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"blockcentre aligncenter wp-image-1257\" src=\"https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-02-300x169.jpeg\" alt=\"\" width=\"500\" height=\"281\" srcset=\"https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-02-300x169.jpeg?v=1678189264 300w, https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-02-768x432.jpeg?v=1678189264 768w, https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-02-18x10.jpeg?v=1678189264 18w, https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-02.jpeg?v=1678189264 1024w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Des \u00e9changes avec certains pays africains fr\u00e8res en termes de partage d\u2019exp\u00e9rience pour le d\u00e9veloppement des secteurs miniers de nos Etats sont aussi \u00e0 l\u2019ordre du jour. Dans ce cadre, il faut pr\u00e9ciser au cours des \u00e9changes que les probl\u00e9matiques sont similaires ainsi que les facteurs bloquants l\u2019\u00e9mergence de ce secteur en Afrique. La n\u00e9cessit\u00e9 d\u2019amplifier les \u00e9changes s\u2019en est d\u00e9gag\u00e9e, tout comme le partage d\u2019informations, et la collaboration dans la recherche des partenaires.<\/p>\n<p>Aujourd\u2019hui, journ\u00e9e cruciale avec la prise de parole de Monsieur le Directeur G\u00e9n\u00e9ral au Sheraton h\u00f4tel, \u00e0 l\u2019occasion du 21\u00e8me s\u00e9minaire annuel sur l\u2019exploitation mini\u00e8re en Afrique qui se tient en marge du PDAC. Ce sera l\u2019occasion de donner \u00e0 voir le potentiel minier camerounais, les projets \u00e0 d\u00e9velopper et les opportunit\u00e9s d\u2019investissements.<\/p>\n<p>En rappel, l\u2019Association Canadienne des Prospecteurs et Entrepreneurs, qui organise cet \u00e9v\u00e8nement repr\u00e9sente les int\u00e9r\u00eats de l\u2019Industrie canadienne d\u2019exploration et de mise en valeur des minerais depuis 1932.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le bras op\u00e9rationnel de l\u2019Etat brave les temp\u00e9ratures hivernales de la ville de Toronto au Canada, pour mettre en vitrine [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-1255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activite"],"uagb_featured_image_src":{"full":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04.jpeg?v=1678193479",1024,576,false],"thumbnail":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04-150x150.jpeg?v=1678193479",150,150,true],"medium":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04-300x169.jpeg?v=1678193479",300,169,true],"medium_large":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04-768x432.jpeg?v=1678193479",640,360,true],"large":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04.jpeg?v=1678193479",640,360,false],"1536x1536":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04.jpeg?v=1678193479",1024,576,false],"2048x2048":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04.jpeg?v=1678193479",1024,576,false],"trp-custom-language-flag":["https:\/\/sonamines.cm\/wp-content\/uploads\/2023\/03\/sonamines-pdac-2023-04-18x10.jpeg?v=1678193479",18,10,true]},"uagb_author_info":{"display_name":"SANDIE Gilles","author_link":"https:\/\/sonamines.cm\/en\/author\/gillessandie\/"},"uagb_comment_info":0,"uagb_excerpt":"Le bras op\u00e9rationnel de l\u2019Etat brave les temp\u00e9ratures hivernales de la ville de Toronto au Canada, pour mettre en vitrine [&hellip;]","_links":{"self":[{"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/posts\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/comments?post=1255"}],"version-history":[{"count":0,"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/posts\/1255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/media\/1263"}],"wp:attachment":[{"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/media?parent=1255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/categories?post=1255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonamines.cm\/en\/wp-json\/wp\/v2\/tags?post=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}